{"id":6703,"date":"2020-12-14T10:16:46","date_gmt":"2020-12-14T09:16:46","guid":{"rendered":"https:\/\/www.devlhon-consulting.com\/?p=6703"},"modified":"2020-12-14T12:03:12","modified_gmt":"2020-12-14T11:03:12","slug":"le-mecanisme-europeen-de-stabilite-au-secours-des-banques","status":"publish","type":"post","link":"https:\/\/www.devlhon-consulting.com\/fr\/le-mecanisme-europeen-de-stabilite-au-secours-des-banques\/","title":{"rendered":"Le m\u00e9canisme europ\u00e9en de stabilit\u00e9 au secours des banques"},"content":{"rendered":"<p>Les Ministres des finances de la zone euro sont tomb\u00e9s d\u2019accord pour renforcer le M\u00e9canisme europ\u00e9en de stabilit\u00e9 (MES) et lui permettre, en cas de grave crise bancaire, d\u2019intervenir en dernier recours. L\u2019accord a \u00e9t\u00e9 salu\u00e9 comme une \u00ab \u00e9tape cruciale \u00bb dans la construction de l\u2019Union bancaire europ\u00e9enne par Paschal Donohoe, le Pr\u00e9sident de l\u2019Eurogroupe. En quoi ? Si les m\u00e9dias soulignent \u00e9galement une avanc\u00e9e europ\u00e9enne importante, ils ne disent gu\u00e8re en quoi elle consiste. Quelques lignes d\u2019explication s\u2019imposent donc car cet accord est effectivement important.<\/p>\n<p>Bien entendu, il faut le comprendre dans le contexte actuel de crise qui va se traduire in\u00e9vitablement par des d\u00e9faillances d\u2019entreprises, lesquelles vont impacter la sant\u00e9 des banques. Actuellement, si certains secteurs sont d\u00e9j\u00e0 gravement touch\u00e9s, on n\u2019appr\u00e9hende encore exactement ni l\u2019ampleur de la casse pour les banques, ni le moment o\u00f9 elle pourra survenir. Mais, quoi qu\u2019il en soit, des d\u00e9faillances de banques sont envisageables et, pour y faire face, quel dispositif europ\u00e9en peut-il \u00eatre mobilis\u00e9 ?<\/p>\n<p>Un M\u00e9canisme de r\u00e9solution unique, qui instaure une supervision europ\u00e9enne au sauvetage des banques. Il s\u2019appuie sur un Fonds de r\u00e9solution unique correspondant \u00e0 1% des d\u00e9p\u00f4ts collect\u00e9s par les \u00e9tablissements de la zone euro. Autant dire rien du tout\u00a0! A peine 55 milliards \u20ac (le fonds n\u2019a pas encore \u00e9t\u00e9 totalement rempli \u00e0 cette hauteur selon le calendrier qui lui avait \u00e9t\u00e9 fix\u00e9), abond\u00e9s par les \u00e9tablissements eux-m\u00eames (afin que la charge des d\u00e9faillances ne soit pas directement support\u00e9e par les contribuables europ\u00e9ens comme ce fut le cas suite \u00e0 la crise de 2008).<\/p>\n<p>Quelle utilit\u00e9 pourrait avoir un fonds aussi faiblement dot\u00e9 face \u00e0 la d\u00e9faillance d\u2019\u00e9tablissements dont la taille des actifs, pour les plus importants d\u2019entre eux, peut d\u00e9passer le PIB de leurs propres Etats ? Il avait donc \u00e9t\u00e9 pr\u00e9vu que le MES puisse intervenir en compl\u00e9ment, au moins le temps que le fonds soit constitu\u00e9 et c\u2019est cette intervention possible qui a \u00e9t\u00e9 ent\u00e9rin\u00e9e et renforc\u00e9e lundi, \u00e0 travers un filet de s\u00e9curit\u00e9 que le MES pourra mobiliser en appui des interventions du M\u00e9canisme de r\u00e9solution unique.<\/p>\n<p>Cet appui, toutefois, ne pourra intervenir qu\u2019en dernier recours, si le Conseil de r\u00e9solution unique n\u2019est pas en mesure de compl\u00e9ter ses moyens propres d\u2019une autre mani\u00e8re \u2013 entendez\u00a0: en mobilisant la Banque centrale europ\u00e9enne, dont les interventions de type LTRO en appui des banques ont d\u00e9j\u00e0 prouv\u00e9 leur efficacit\u00e9.<\/p>\n<p>A vrai dire, les moyens dont dispose la BCE sont si importants et sa volont\u00e9 de les utiliser le cas \u00e9ch\u00e9ant fait si peu de doute qu\u2019on peut se demander si la contribution possible du MES n\u2019est pas plus symbolique que v\u00e9ritablement utile. Et c\u2019est ici qu\u2019une explication de texte est n\u00e9cessaire.<\/p>\n<p>Souvent pr\u00e9sent\u00e9 comme une sorte de FMI europ\u00e9en et constitu\u00e9 \u00e0 l\u2019issue de la crise grecque, le MES a \u00e9t\u00e9 mis sur pieds pour faire face \u00e0 la d\u00e9faillance possible des Etats europ\u00e9ens et non uniquement des banques. Dans le contexte actuel, qui a vu dangereusement bondir l\u2019endettement de plusieurs pays, dont la France, la mobilisation du MES reconnait ainsi \u2013 sans le dire explicitement \u00a0\u2013 que la d\u00e9gradation de la cote de confiance des Etats repr\u00e9sente l\u2019un des principaux (sinon le principal) risques qui p\u00e8sent sur des \u00e9tablissements financiers porteurs (notamment du fait de la r\u00e9glementation bancaire) de tr\u00e8s cons\u00e9quents portefeuilles de dettes souveraines. On en parle pourtant assez rarement\u2026<\/p>\n<p>L\u2019autre novation ent\u00e9rin\u00e9e par l\u2019accord tient au fait qu\u2019une intervention en dernier recours pour sauver des \u00e9tablissements consisterait le plus probablement en une recapitalisation. Or celle-ci, donnant potentiellement aux cr\u00e9anciers de dernier recours le contr\u00f4le des \u00e9tablissements eux-m\u00eames, aura d\u00e9sormais lieu sous une supervision europ\u00e9enne et non plus selon de seules initiatives nationales, comme cela fut le cas en 2008. Une supervision exerc\u00e9e par le MES, au sein duquel trois pays \u2013 l\u2019Allemagne, la France et l\u2019Italie \u2013 disposent d\u2019un droit de v\u00e9to.<\/p>\n<p>Une crise grave comme celle de 2008, si elle survenait dans les ann\u00e9es qui viennent, pourrait ainsi ouvrir la possibilit\u00e9 de recomposer de mani\u00e8re significative et strat\u00e9gique le paysage bancaire europ\u00e9en. Cela m\u00e9ritait d\u2019\u00eatre soulign\u00e9.<\/p>\n<p>Score Advisor<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Les Ministres des finances de la zone euro sont tomb\u00e9s d\u2019accord pour renforcer le M\u00e9canisme europ\u00e9en de stabilit\u00e9 (MES) et lui permettre, en cas de grave crise bancaire, d\u2019intervenir en dernier recours. L\u2019accord a \u00e9t\u00e9 salu\u00e9 comme une \u00ab \u00e9tape cruciale \u00bb dans la construction de l\u2019Union bancaire europ\u00e9enne par Paschal Donohoe, le Pr\u00e9sident de [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":6361,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"seo_booster_metabox":"","footnotes":""},"categories":[47,137],"tags":[72,76],"class_list":["post-6703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-devlhon-consulting","category-article","tag-banque","tag-devlhon-consulting"],"amp_validity":null,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.devlhon-consulting.com\/fr\/wp-json\/wp\/v2\/posts\/6703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.devlhon-consulting.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.devlhon-consulting.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.devlhon-consulting.com\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.devlhon-consulting.com\/fr\/wp-json\/wp\/v2\/comments?post=6703"}],"version-history":[{"count":3,"href":"https:\/\/www.devlhon-consulting.com\/fr\/wp-json\/wp\/v2\/posts\/6703\/revisions"}],"predecessor-version":[{"id":6707,"href":"https:\/\/www.devlhon-consulting.com\/fr\/wp-json\/wp\/v2\/posts\/6703\/revisions\/6707"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.devlhon-consulting.com\/fr\/wp-json\/wp\/v2\/media\/6361"}],"wp:attachment":[{"href":"https:\/\/www.devlhon-consulting.com\/fr\/wp-json\/wp\/v2\/media?parent=6703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.devlhon-consulting.com\/fr\/wp-json\/wp\/v2\/categories?post=6703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.devlhon-consulting.com\/fr\/wp-json\/wp\/v2\/tags?post=6703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}